{"id":16432,"date":"2021-06-24T10:00:49","date_gmt":"2021-06-24T08:00:49","guid":{"rendered":"https:\/\/heymondo.es\/blog\/?p=16432"},"modified":"2024-05-14T18:40:47","modified_gmt":"2024-05-14T16:40:47","slug":"que-ver-en-alsacia","status":"publish","type":"post","link":"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/","title":{"rendered":"Que ver en Alsacia: Una ruta por los encantos de Alsacia"},"content":{"rendered":"<blockquote><p>Tom\u00e1s Garcia, autor del blog <strong>\u2018Viajero Cr\u00f3nico\u2019<\/strong>, cuenta experiencias, an\u00e9cdotas y consejos sobre los <strong>m\u00e1s de 50 pa\u00edses<\/strong> que ha visitado alrededor del mundo.<\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Coloridas casas con entramados de madera, coquetos pueblos sacados de un cuento, ruinas de castillos en altas colinas o una rica gastronom\u00eda son algunas de las atracciones de una <strong>ruta por la regi\u00f3n de Alsacia, una de las regiones m\u00e1s encantadoras de Francia<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los primeros pasos en la regi\u00f3n enamoran al m\u00e1s esc\u00e9ptico, porque s\u00ed, son muchos los <\/span><strong><a href=\"https:\/\/cronicoviajero.com\/que-ver-alsacia\/\" target=\"_blank\" rel=\"noopener noreferrer\">lugares imprescindibles que ver en Alsacia<\/a><\/strong><span style=\"font-weight: 400;\"> y todos acabamos pasando por algunos puntos comunes, algo que puede generar dudas a quienes busquen lugares menos tur\u00edsticos, pero es probable que, cuando se habla de su belleza, se trate de uno de los lugares que m\u00e1s consense genere.<\/span><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 ez-toc-wrap-center counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/#Colmar_la_base_mas_encantadora_para_explorar_Alsacia\" >Colmar, la base m\u00e1s encantadora para explorar Alsacia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/#Ruta_por_los_pueblos_alsacianos_en_busca_de_fotografias_inolvidables\" >Ruta por los pueblos alsacianos, en busca de fotograf\u00edas inolvidables<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/#Alsacia_tierra_de_castillos%E2%80%A6\" >Alsacia, tierra de castillos\u2026<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/#%E2%80%A6y_de_vinos\" >\u2026y de vinos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/#La_mejor_epoca_para_visitar_Alsacia\" >La mejor \u00e9poca para visitar Alsacia<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Colmar_la_base_mas_encantadora_para_explorar_Alsacia\"><\/span><b>Colmar, la base m\u00e1s encantadora para explorar Alsacia<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><a href=\"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Colmar-scaled-1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-16542\" src=\"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Colmar-scaled-1.jpg\" alt=\"Colmar, Alsacia\" width=\"2560\" height=\"1440\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Hablar de Alsacia es hacerlo de <strong>Colmar, puede que<\/strong> <strong>la ciudad m\u00e1s famosa de la regi\u00f3n<\/strong> y probablemente una de las bases m\u00e1s habituales para alojarse para aquellos que busquen visitar la zona.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Colmar tiene un tama\u00f1o bastante mayor al de muchos pueblos alsacianos, pero ha conservado su encanto, <strong>sobre todo en su centro hist\u00f3rico<\/strong>, donde las casas con los populares y fotog\u00e9nicos entramados de madera acompa\u00f1an a cada paso. Es dif\u00edcil resistirse a hacer una parada cada pocos metros para sacar una foto en lugares <strong>como la<\/strong> <strong>Rue des Marchands<\/strong> <strong>o la<\/strong> <strong>Place de l\u2019Ancienne Douane<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>El punto \u00e1lgido de la<\/strong> <strong>visita a Colmar<\/strong>, eso s\u00ed, aparece cuando el viajero llega a <strong>la Petite Venise<\/strong>, conocida as\u00ed por sus canales y donde la escena parece pintada. Las vistas desde los peque\u00f1os puentes que cruzan en canal principal dejan boquiabierto a cualquiera.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una vez uno ha conocido todos los atractivos de Colmar, como<strong> la Maison des Tetes<\/strong> o la bonita <strong>Iglesia de los Dominicos<\/strong> de la <strong>plaza des Dominicains<\/strong>, hay que organizar bien la ruta, porque lo mejor de Alsacia todav\u00eda est\u00e1 por llegar.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Ruta_por_los_pueblos_alsacianos_en_busca_de_fotografias_inolvidables\"><\/span><b>Ruta por los pueblos alsacianos, en busca de fotograf\u00edas inolvidables<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><a href=\"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Riquewihr-scaled-1.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-16543 size-full\" src=\"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Riquewihr-scaled-1.jpg\" alt=\"Riquewihr\" width=\"2560\" height=\"1440\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Los pueblos alsacianos son lo que de verdad va a acabar enamor\u00e1ndote de esta regi\u00f3n. Peque\u00f1os y encantadores, algunos son dos simples calles, mientras que otros son peque\u00f1as aldeas que <strong>parecen salir directamente de un cuento<\/strong> o que aparecen en mitad de grandes extensiones de vi\u00f1edos. Todos tienen historias y leyendas que hacen que la visita, adem\u00e1s de est\u00e9tica, sea muy interesante.<\/span><\/p>\n<p><b>Eguisheim<\/b><span style=\"font-weight: 400;\"><strong> es la primera parada<\/strong>, una aldea amurallada cuya forma circular es \u00fanica y donde se encuentra una de las postales m\u00e1s populares de la zona,<strong> la famosa Le Pigeonnier<\/strong>, que da acceso a trav\u00e9s de dos bifurcaciones a las bonitas calles adoquinadas del pueblo. No es de extra\u00f1ar que Eguisheim haya copado varias listas de los pueblos m\u00e1s bonitos de Francia durante a\u00f1os.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desde aqu\u00ed se llega en poco tiempo a <strong>Les Trois Chateaux, una corta excursi\u00f3n que conduce hasta las ruinas de tres castillos<\/strong> que ya valen la pena por s\u00ed solas, pero cuyas vistas de la zona te dejan deslumbrado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La ruta sigue en pueblos como <\/span><b>Riquewihr<\/b><strong>, donde se encuentra el <i>Gratte-Ciel<\/i><\/strong><span style=\"font-weight: 400;\">, conocido con ese sobrenombre por tratarse de <strong>la casa con entramado de madera m\u00e1s alta de la Alsacia<\/strong> o <\/span><b>Gertwiller<\/b><span style=\"font-weight: 400;\">, diminuto, pero con su famoso <strong>Museo del Pain d\u2019\u00e9pices<\/strong>, donde podr\u00e1s comprobar de primera mano lo delicioso que est\u00e1 este dulce t\u00edpico alsaciano.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para quienes busquen historias interesantes, en el peque\u00f1o <\/span><b>Hunawihr<\/b><span style=\"font-weight: 400;\"> se encuentra su iglesia, destacable por tratarse de uno de los contados ejemplos de<strong> arquitectura religiosa defensiva<\/strong> que todav\u00eda quedan en pie. La visita no decepciona y adem\u00e1s, las vistas de los cercanos vi\u00f1edos forman una estampa deliciosa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Siguiendo la <strong>ruta en coche por la regi\u00f3n<\/strong>, a muy poca distancia se encuentran las localidades de <\/span><b>Barr<\/b><span style=\"font-weight: 400;\"> y <\/span><b>Obernai<\/b><span style=\"font-weight: 400;\">, la primera, m\u00e1s alternativa y mucho menos tur\u00edstica, con bonitos callejones y colores, mientras que la segunda, m\u00e1s grande y popular, tiene en su bonita plaza central uno de los rincones m\u00e1s bonitos de Alsacia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El d\u00fao que forman <\/span><b>Bergheim<\/b><span style=\"font-weight: 400;\"> y <\/span><b>Turckheim<\/b><span style=\"font-weight: 400;\"> es nuestra siguiente parada. Aqu\u00ed no hay m\u00e1s que perderse y deambular por su entramado de callejuelas adoquinadas para disfrutar de la pura Alsacia y llevarse algunas de las mejores im\u00e1genes del viaje.<\/span><\/p>\n<p><a href=\"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Ribeauville-scaled-1.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-16546 size-full\" src=\"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Ribeauville-scaled-1.jpg\" alt=\"pueblo con encanto\" width=\"2560\" height=\"1440\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Siguiendo la ruta, aparece otra de esas localidades que encandilan y que, sin embargo, no se encuentra entre las m\u00e1s visitadas: <\/span><b>Ribeauvill\u00e9<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Su arteria central, una avenida peatonal con coloridas casas que la flanquean a ambos lados, mira siempre a las ruinas de su castillo, que se atisban en el horizonte imponentes y orgullosas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hemos dejado para el final de ruta a <\/span><b>Kayserberg<\/b><span style=\"font-weight: 400;\">, porque no hay mejor manera de acabar que con este precioso <strong>pueblo por el que cruza el r\u00edo Weiss<\/strong> y que muchos consideran el pueblo m\u00e1s bonito de Alsacia. <strong>En 2017 fue elegido como el pueblo preferido de los franceses<\/strong> y desde que lo conoc\u00ed, tambi\u00e9n es mi favorito.<\/span><\/p>\n<p><a href=\"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Kayserberg-scaled-1.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-16547 size-full\" src=\"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Kayserberg-scaled-1.jpg\" alt=\"que ver en Alsacia\" width=\"2560\" height=\"1440\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">La ruta podr\u00eda seguir por una lista casi interminable de pueblos, como <strong>Dambach-la-Ville<\/strong>, Mittelbergheim, Itterswiller o Thannenkirch, cada una con sus peculiaridades pero con un encanto \u00fanico.<\/span><\/p>\n<p><a href=\"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Dambach-la-Ville-scaled-1.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-16545 size-full\" src=\"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Dambach-la-Ville-scaled-1.jpg\" alt=\"ruta por Alsacia\" width=\"2560\" height=\"1641\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Lo ideal es hacer al menos una <\/span><strong><a href=\"https:\/\/cronicoviajero.com\/3-dias-en-alsacia-itinerario\/\" target=\"_blank\" rel=\"noopener noreferrer\">ruta de 3 d\u00edas en Alsacia<\/a><\/strong><span style=\"font-weight: 400;\">, suficiente para conocer la mayor parte de sus imprescindibles, aunque todo lo que sobrepase esa duraci\u00f3n te permitir\u00e1 descubrir otros lugares, en ocasiones menos famosos y que no aparecen en los grandes itinerarios.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Alsacia_tierra_de_castillos%E2%80%A6\"><\/span><b>Alsacia, tierra de castillos\u2026<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><a href=\"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Castillo-de-Haut-Koenigsbourg-scaled-1.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-16544 size-full\" src=\"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Castillo-de-Haut-Koenigsbourg-scaled-1.jpg\" alt=\"Castillos en Alsacia\" width=\"2560\" height=\"1504\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Uno es el castillo por excelencia de <strong>Alsacia<\/strong>, el archifamoso <\/span><b>castillo de Haut-Koenigsburg<\/b><span style=\"font-weight: 400;\">, restaurado para permitir las visitas y que es, sin duda, uno de los grandes <\/span><i><span style=\"font-weight: 400;\">highlights<\/span><\/i><span style=\"font-weight: 400;\"> que ver en Alsacia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Donado por <strong>Carlomagno en el siglo VIII<\/strong>, fue un punto de <strong>especial relevancia estrat\u00e9gica en las rutas comerciales<\/strong> y por ello sufri\u00f3 varios intentos de conquista que lo dejaron casi en ruinas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero si por algo tambi\u00e9n se caracteriza esta regi\u00f3n es por su lista casi infinita de ruinas de castillos. Muchos, de manera casi inesperada, aparecen en el horizonte sobre una colina y permiten llegar en tu veh\u00edculo, como el de <\/span><b>Hohlandsbourg<\/b><span style=\"font-weight: 400;\">. Otros ni siquiera eso, y hay que equiparse con un buen calzado para llegar hasta ellos, como los castillos de <\/span><b>Girsberg<\/b><span style=\"font-weight: 400;\">,\u00a0<\/span><b>Saint-Ulrich<\/b><span style=\"font-weight: 400;\">\u00a0y\u00a0<\/span><b>Haut-Ribeaupierre.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Los castillos de <strong>Ortenbourg<\/strong>, <strong>Ramstein<\/strong> o <strong>Bernstein<\/strong> son otros, aunque la mejor recomendaci\u00f3n que se puede hacer es que te atrevas con cualquier que aparezca ante tu mirada<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E2%80%A6y_de_vinos\"><\/span><b>\u2026y de vinos<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Y qu\u00e9 mejor manera de acabar una<strong> ruta por Alsacia<\/strong> que hacerlo con un buen vino. <\/span><span style=\"font-weight: 400;\">De hecho, se conoce a esta ruta como la \u2018<strong>Ruta de los Vinos\u2019<\/strong> y cruzar\u00e1s constantemente grandes extensiones de vi\u00f1edos que forman un bonito paisaje. <\/span><span style=\"font-weight: 400;\">Aqu\u00ed se cultivan muchas variedades, pero algunas como <strong>la gewurztraminer, el pinot gris, el pinot blanc o sylvaner, son las m\u00e1s populares<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Menci\u00f3n aparte para la variedad riesling, puede que la m\u00e1s extendida en la Alsacia y cuyos vinos han dado fama mundial a la regi\u00f3n.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"La_mejor_epoca_para_visitar_Alsacia\"><\/span><b>La mejor \u00e9poca para visitar Alsacia<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Puede que<strong> en Navidad<\/strong>, cuando empiezan a montarse sus famosos mercadillos navide\u00f1os,<strong> sea la \u00e9poca m\u00e1s popular<\/strong> para hacer un viaje a Alsacia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las luces, el ambiente navide\u00f1o, el movimiento y la exquisita y cuidada decoraci\u00f3n de todos y cada uno de los pueblos, <strong>han convertido a Alsacia en una de las visitas por excelencia en esta \u00e9poca de a\u00f1o.<\/strong> No ser\u00e9 yo quien os diga lo contrario, pero olv\u00eddate de la calma y la tranquilidad y prepara con antelaci\u00f3n el viaje si no quieres quedarte sin alojamiento o sin sitio en un restaurante que te hayan recomendado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por otro lado, <strong>la \u00e9poca estival, principalmente en septiembre<\/strong>, parece otra distinta, <strong>tranquila, calmada, transcurriendo a ritmo lento<\/strong> y permitiendo saborear cada rinc\u00f3n de una regi\u00f3n camale\u00f3nica y pintoresca como es Alsacia.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tom\u00e1s Garcia, autor del blog \u2018Viajero Cr\u00f3nico\u2019, cuenta experiencias, an\u00e9cdotas  ..<\/p>\n","protected":false},"author":2,"featured_media":16542,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[60],"tags":[],"class_list":["post-16432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destinos-y-rutas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Que ver en Alsacia: Una ruta por los encantos de Alsacia<\/title>\n<meta name=\"description\" content=\"Que ver en Alsacia: Una ruta por los rinconces con m\u00e1s encanto de la Alsacia Francesa. No te pierdas este destino lleno de encanto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Que ver en Alsacia: Una ruta por los encantos de Alsacia\" \/>\n<meta property=\"og:description\" content=\"Que ver en Alsacia: Una ruta por los rinconces con m\u00e1s encanto de la Alsacia Francesa. No te pierdas este destino lleno de encanto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/\" \/>\n<meta property=\"og:site_name\" content=\"Heymondo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/heymondoes\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-24T08:00:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-14T16:40:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Colmar-scaled-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1421\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Judith Lopez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@HeymondoEs\" \/>\n<meta name=\"twitter:site\" content=\"@HeymondoEs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Judith Lopez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/que-ver-en-alsacia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/que-ver-en-alsacia\\\/\"},\"author\":{\"name\":\"Judith Lopez\",\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/#\\\/schema\\\/person\\\/13988fada377679e041fbbc4a29fa0b6\"},\"headline\":\"Que ver en Alsacia: Una ruta por los encantos de Alsacia\",\"datePublished\":\"2021-06-24T08:00:49+00:00\",\"dateModified\":\"2024-05-14T16:40:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/que-ver-en-alsacia\\\/\"},\"wordCount\":1355,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/que-ver-en-alsacia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Colmar-scaled-1-scaled.jpg\",\"articleSection\":[\"Destinos y rutas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/heymondo.es\\\/blog\\\/que-ver-en-alsacia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/que-ver-en-alsacia\\\/\",\"url\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/que-ver-en-alsacia\\\/\",\"name\":\"Que ver en Alsacia: Una ruta por los encantos de Alsacia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/que-ver-en-alsacia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/que-ver-en-alsacia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Colmar-scaled-1-scaled.jpg\",\"datePublished\":\"2021-06-24T08:00:49+00:00\",\"dateModified\":\"2024-05-14T16:40:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/#\\\/schema\\\/person\\\/13988fada377679e041fbbc4a29fa0b6\"},\"description\":\"Que ver en Alsacia: Una ruta por los rinconces con m\u00e1s encanto de la Alsacia Francesa. No te pierdas este destino lleno de encanto.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/que-ver-en-alsacia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/heymondo.es\\\/blog\\\/que-ver-en-alsacia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/que-ver-en-alsacia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Colmar-scaled-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Colmar-scaled-1-scaled.jpg\",\"width\":1421,\"height\":800,\"caption\":\"Colmar, Alsacia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/que-ver-en-alsacia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Que ver en Alsacia: Una ruta por los encantos de Alsacia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/\",\"name\":\"Heymondo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/#\\\/schema\\\/person\\\/13988fada377679e041fbbc4a29fa0b6\",\"name\":\"Judith Lopez\",\"description\":\"Judith es Affiliate Manager en Heymondo y es una apasionada de los viajes y el aprendizaje en cualquiera de sus formas. En el blog de Heymondo, combina su experiencia profesional con su entusiasmo por aprender sobre nuevas culturas y destinos, que naci\u00f3 de sus primeros viajes en familia por Europa, brindando recomendaciones valiosas y perspectivas frescas para los viajeros. En sus textos, Judith se centra en compartir consejos \u00fatiles as\u00ed como en inspirar aventuras memorables en diferentes rincones del mundo.\",\"url\":\"https:\\\/\\\/heymondo.es\\\/blog\\\/author\\\/judith\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Que ver en Alsacia: Una ruta por los encantos de Alsacia","description":"Que ver en Alsacia: Una ruta por los rinconces con m\u00e1s encanto de la Alsacia Francesa. No te pierdas este destino lleno de encanto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/","og_locale":"es_ES","og_type":"article","og_title":"Que ver en Alsacia: Una ruta por los encantos de Alsacia","og_description":"Que ver en Alsacia: Una ruta por los rinconces con m\u00e1s encanto de la Alsacia Francesa. No te pierdas este destino lleno de encanto.","og_url":"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/","og_site_name":"Heymondo","article_publisher":"https:\/\/www.facebook.com\/heymondoes\/","article_published_time":"2021-06-24T08:00:49+00:00","article_modified_time":"2024-05-14T16:40:47+00:00","og_image":[{"width":1421,"height":800,"url":"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Colmar-scaled-1-scaled.jpg","type":"image\/jpeg"}],"author":"Judith Lopez","twitter_card":"summary_large_image","twitter_creator":"@HeymondoEs","twitter_site":"@HeymondoEs","twitter_misc":{"Escrito por":"Judith Lopez","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/#article","isPartOf":{"@id":"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/"},"author":{"name":"Judith Lopez","@id":"https:\/\/heymondo.es\/blog\/#\/schema\/person\/13988fada377679e041fbbc4a29fa0b6"},"headline":"Que ver en Alsacia: Una ruta por los encantos de Alsacia","datePublished":"2021-06-24T08:00:49+00:00","dateModified":"2024-05-14T16:40:47+00:00","mainEntityOfPage":{"@id":"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/"},"wordCount":1355,"commentCount":0,"image":{"@id":"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/#primaryimage"},"thumbnailUrl":"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Colmar-scaled-1-scaled.jpg","articleSection":["Destinos y rutas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/","url":"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/","name":"Que ver en Alsacia: Una ruta por los encantos de Alsacia","isPartOf":{"@id":"https:\/\/heymondo.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/#primaryimage"},"image":{"@id":"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/#primaryimage"},"thumbnailUrl":"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Colmar-scaled-1-scaled.jpg","datePublished":"2021-06-24T08:00:49+00:00","dateModified":"2024-05-14T16:40:47+00:00","author":{"@id":"https:\/\/heymondo.es\/blog\/#\/schema\/person\/13988fada377679e041fbbc4a29fa0b6"},"description":"Que ver en Alsacia: Una ruta por los rinconces con m\u00e1s encanto de la Alsacia Francesa. No te pierdas este destino lleno de encanto.","breadcrumb":{"@id":"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/#primaryimage","url":"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Colmar-scaled-1-scaled.jpg","contentUrl":"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Colmar-scaled-1-scaled.jpg","width":1421,"height":800,"caption":"Colmar, Alsacia"},{"@type":"BreadcrumbList","@id":"https:\/\/heymondo.es\/blog\/que-ver-en-alsacia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/heymondo.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Que ver en Alsacia: Una ruta por los encantos de Alsacia"}]},{"@type":"WebSite","@id":"https:\/\/heymondo.es\/blog\/#website","url":"https:\/\/heymondo.es\/blog\/","name":"Heymondo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/heymondo.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/heymondo.es\/blog\/#\/schema\/person\/13988fada377679e041fbbc4a29fa0b6","name":"Judith Lopez","description":"Judith es Affiliate Manager en Heymondo y es una apasionada de los viajes y el aprendizaje en cualquiera de sus formas. En el blog de Heymondo, combina su experiencia profesional con su entusiasmo por aprender sobre nuevas culturas y destinos, que naci\u00f3 de sus primeros viajes en familia por Europa, brindando recomendaciones valiosas y perspectivas frescas para los viajeros. En sus textos, Judith se centra en compartir consejos \u00fatiles as\u00ed como en inspirar aventuras memorables en diferentes rincones del mundo.","url":"https:\/\/heymondo.es\/blog\/author\/judith\/"}]}},"featured_image_url":"https:\/\/heymondo.es\/blog\/wp-content\/uploads\/2021\/06\/Colmar-scaled-1-scaled.jpg","_links":{"self":[{"href":"https:\/\/heymondo.es\/blog\/wp-json\/wp\/v2\/posts\/16432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heymondo.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/heymondo.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/heymondo.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/heymondo.es\/blog\/wp-json\/wp\/v2\/comments?post=16432"}],"version-history":[{"count":1,"href":"https:\/\/heymondo.es\/blog\/wp-json\/wp\/v2\/posts\/16432\/revisions"}],"predecessor-version":[{"id":41929,"href":"https:\/\/heymondo.es\/blog\/wp-json\/wp\/v2\/posts\/16432\/revisions\/41929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/heymondo.es\/blog\/wp-json\/wp\/v2\/media\/16542"}],"wp:attachment":[{"href":"https:\/\/heymondo.es\/blog\/wp-json\/wp\/v2\/media?parent=16432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/heymondo.es\/blog\/wp-json\/wp\/v2\/categories?post=16432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/heymondo.es\/blog\/wp-json\/wp\/v2\/tags?post=16432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}